{"id":1121,"date":"2022-09-23T06:22:31","date_gmt":"2022-09-23T06:22:31","guid":{"rendered":"https:\/\/diamondtvzambia.com\/staging\/7839\/?p=1121"},"modified":"2022-09-23T06:22:47","modified_gmt":"2022-09-23T06:22:47","slug":"eagles-of-mali-geared-for-chipolopolo-showdown","status":"publish","type":"post","link":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/","title":{"rendered":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"607\" src=\"https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1.jpg?resize=1024%2C607&#038;ssl=1\" alt=\"\" class=\"wp-image-1122\" srcset=\"https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1.jpg?resize=1024%2C607&amp;ssl=1 1024w, https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1.jpg?resize=300%2C178&amp;ssl=1 300w, https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1.jpg?resize=768%2C455&amp;ssl=1 768w, https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1.jpg?w=1080&amp;ssl=1 1080w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">For <a><\/a>this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper Bullets tomorrow on September 23 and 26.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meanwhile Chipolopolo midfielder Klings Kangwa who joined the team yesterday says the team is looking forward to the games<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">By Cosmas Chongo Mulenga<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper &hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","content-type":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1121","post","type-post","status-publish","format-standard","hentry","category-sports"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Editor 2\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Diamond Media -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media\" \/>\n\t\t<meta property=\"og:description\" content=\"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/diamondtvzambia.com\/wp-content\/uploads\/2022\/09\/cropped-Diamond-Logo-SOLO.png?fit=158155&#038;ssl=1\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/i0.wp.com\/diamondtvzambia.com\/wp-content\/uploads\/2022\/09\/cropped-Diamond-Logo-SOLO.png?fit=158155&#038;ssl=1\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-09-23T06:22:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-23T06:22:47+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/i0.wp.com\/diamondtvzambia.com\/wp-content\/uploads\/2022\/09\/cropped-Diamond-Logo-SOLO.png?fit=158155&amp;ssl=1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#blogposting\",\"name\":\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media\",\"headline\":\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN\",\"author\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/author\\\/editor-2\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/chipolopolo-1.jpg?fit=1080%2C640&ssl=1\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#articleImage\",\"width\":1080,\"height\":640},\"datePublished\":\"2022-09-23T06:22:31+00:00\",\"dateModified\":\"2022-09-23T06:22:47+00:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#webpage\"},\"articleSection\":\"Sports\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/category\\\/sports\\\/#listItem\",\"name\":\"Sports\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/category\\\/sports\\\/#listItem\",\"position\":2,\"name\":\"Sports\",\"item\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/category\\\/sports\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#listItem\",\"name\":\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#listItem\",\"position\":3,\"name\":\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/category\\\/sports\\\/#listItem\",\"name\":\"Sports\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/#organization\",\"name\":\"Diamond Media\",\"url\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/author\\\/editor-2\\\/#author\",\"url\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/author\\\/editor-2\\\/\",\"name\":\"Editor 2\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52331c099be5016e4ead90a1b22019537520b80ea8d3cc4ce734bd2293679c70?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Editor 2\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#webpage\",\"url\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/\",\"name\":\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media\",\"description\":\"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/author\\\/editor-2\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/author\\\/editor-2\\\/#author\"},\"datePublished\":\"2022-09-23T06:22:31+00:00\",\"dateModified\":\"2022-09-23T06:22:47+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/#website\",\"url\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/\",\"name\":\"Diamond Media\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media","description":"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper","canonical_url":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#blogposting","name":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media","headline":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN","author":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/author\/editor-2\/#author"},"publisher":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1.jpg?fit=1080%2C640&ssl=1","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#articleImage","width":1080,"height":640},"datePublished":"2022-09-23T06:22:31+00:00","dateModified":"2022-09-23T06:22:47+00:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#webpage"},"isPartOf":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#webpage"},"articleSection":"Sports"},{"@type":"BreadcrumbList","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/diamondtvzambia.com\/staging\/7839#listItem","position":1,"name":"Home","item":"https:\/\/diamondtvzambia.com\/staging\/7839","nextItem":{"@type":"ListItem","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/category\/sports\/#listItem","name":"Sports"}},{"@type":"ListItem","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/category\/sports\/#listItem","position":2,"name":"Sports","item":"https:\/\/diamondtvzambia.com\/staging\/7839\/category\/sports\/","nextItem":{"@type":"ListItem","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#listItem","name":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN"},"previousItem":{"@type":"ListItem","@id":"https:\/\/diamondtvzambia.com\/staging\/7839#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#listItem","position":3,"name":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN","previousItem":{"@type":"ListItem","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/category\/sports\/#listItem","name":"Sports"}}]},{"@type":"Organization","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/#organization","name":"Diamond Media","url":"https:\/\/diamondtvzambia.com\/staging\/7839\/"},{"@type":"Person","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/author\/editor-2\/#author","url":"https:\/\/diamondtvzambia.com\/staging\/7839\/author\/editor-2\/","name":"Editor 2","image":{"@type":"ImageObject","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/52331c099be5016e4ead90a1b22019537520b80ea8d3cc4ce734bd2293679c70?s=96&d=mm&r=g","width":96,"height":96,"caption":"Editor 2"}},{"@type":"WebPage","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#webpage","url":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/","name":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media","description":"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/#website"},"breadcrumb":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#breadcrumblist"},"author":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/author\/editor-2\/#author"},"creator":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/author\/editor-2\/#author"},"datePublished":"2022-09-23T06:22:31+00:00","dateModified":"2022-09-23T06:22:47+00:00"},{"@type":"WebSite","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/#website","url":"https:\/\/diamondtvzambia.com\/staging\/7839\/","name":"Diamond Media","inLanguage":"en-US","publisher":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/#organization"}}]},"og:locale":"en_US","og:site_name":"Diamond Media -","og:type":"article","og:title":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media","og:description":"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper","og:url":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/","og:image":"https:\/\/i0.wp.com\/diamondtvzambia.com\/wp-content\/uploads\/2022\/09\/cropped-Diamond-Logo-SOLO.png?fit=158155&#038;ssl=1","og:image:secure_url":"https:\/\/i0.wp.com\/diamondtvzambia.com\/wp-content\/uploads\/2022\/09\/cropped-Diamond-Logo-SOLO.png?fit=158155&#038;ssl=1","article:published_time":"2022-09-23T06:22:31+00:00","article:modified_time":"2022-09-23T06:22:47+00:00","twitter:card":"summary_large_image","twitter:title":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media","twitter:description":"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper","twitter:image":"https:\/\/i0.wp.com\/diamondtvzambia.com\/wp-content\/uploads\/2022\/09\/cropped-Diamond-Logo-SOLO.png?fit=158155&ssl=1"},"aioseo_meta_data":{"post_id":"1121","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-09-23 06:22:48","updated":"2025-06-03 23:45:44","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/diamondtvzambia.com\/staging\/7839\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/diamondtvzambia.com\/staging\/7839\/category\/sports\/\" title=\"Sports\">Sports<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/diamondtvzambia.com\/staging\/7839"},{"label":"Sports","link":"https:\/\/diamondtvzambia.com\/staging\/7839\/category\/sports\/"},{"label":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN","link":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/"}],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media\" \/>\n<meta property=\"og:description\" content=\"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/\" \/>\n<meta property=\"og:site_name\" content=\"Diamond Media\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/web.facebook.com\/DiamondTvOnline\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-23T06:22:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-23T06:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1-1024x607.jpg\" \/>\n<meta name=\"author\" content=\"Editor 2\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@diamondtvzambia\" \/>\n<meta name=\"twitter:site\" content=\"@diamondtvzambia\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor 2\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/\"},\"author\":{\"name\":\"Editor 2\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/#\\\/schema\\\/person\\\/9ae61b26a35a38fd83acb1b9f7f4452b\"},\"headline\":\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN\",\"datePublished\":\"2022-09-23T06:22:31+00:00\",\"dateModified\":\"2022-09-23T06:22:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/\"},\"wordCount\":88,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/chipolopolo-1-1024x607.jpg\",\"articleSection\":[\"Sports\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/\",\"url\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/\",\"name\":\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/chipolopolo-1-1024x607.jpg\",\"datePublished\":\"2022-09-23T06:22:31+00:00\",\"dateModified\":\"2022-09-23T06:22:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/chipolopolo-1.jpg?fit=1080%2C640&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/chipolopolo-1.jpg?fit=1080%2C640&ssl=1\",\"width\":1080,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/eagles-of-mali-geared-for-chipolopolo-showdown\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/#website\",\"url\":\"https:\\\/\\\/diamondtvzambia.com\\\/\",\"name\":\"Diamond Media\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diamondtvzambia.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/#organization\",\"name\":\"Diamond Media\",\"url\":\"https:\\\/\\\/diamondtvzambia.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-Logo.png?fit=999%2C999&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/cropped-Logo.png?fit=999%2C999&ssl=1\",\"width\":999,\"height\":999,\"caption\":\"Diamond Media\"},\"image\":{\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/web.facebook.com\\\/DiamondTvOnline\\\/\",\"https:\\\/\\\/x.com\\\/diamondtvzambia\",\"https:\\\/\\\/www.instagram.com\\\/diamondtvsocial\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diamondtvzambia.com\\\/#\\\/schema\\\/person\\\/9ae61b26a35a38fd83acb1b9f7f4452b\",\"name\":\"Editor 2\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52331c099be5016e4ead90a1b22019537520b80ea8d3cc4ce734bd2293679c70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52331c099be5016e4ead90a1b22019537520b80ea8d3cc4ce734bd2293679c70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/52331c099be5016e4ead90a1b22019537520b80ea8d3cc4ce734bd2293679c70?s=96&d=mm&r=g\",\"caption\":\"Editor 2\"},\"url\":\"https:\\\/\\\/diamondtvzambia.com\\\/staging\\\/7839\\\/author\\\/editor-2\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/","og_locale":"en_US","og_type":"article","og_title":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media","og_description":"Having qualified for the Africa Cup of Nations on 12 occasions, the eagles of Mali will use two high class FIFA friendlies against the Chipolopolo as part of preparations for the 2023 Africa Cup of Nations qualifiers. For this clash, Mali Head Coach Eric Sekou Chelle has assembled a 25-member squad to face the Copper &hellip;","og_url":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/","og_site_name":"Diamond Media","article_publisher":"https:\/\/web.facebook.com\/DiamondTvOnline\/","article_published_time":"2022-09-23T06:22:31+00:00","article_modified_time":"2022-09-23T06:22:47+00:00","og_image":[{"url":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1-1024x607.jpg","type":"","width":"","height":""}],"author":"Editor 2","twitter_card":"summary_large_image","twitter_creator":"@diamondtvzambia","twitter_site":"@diamondtvzambia","twitter_misc":{"Written by":"Editor 2"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#article","isPartOf":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/"},"author":{"name":"Editor 2","@id":"https:\/\/diamondtvzambia.com\/#\/schema\/person\/9ae61b26a35a38fd83acb1b9f7f4452b"},"headline":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN","datePublished":"2022-09-23T06:22:31+00:00","dateModified":"2022-09-23T06:22:47+00:00","mainEntityOfPage":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/"},"wordCount":88,"commentCount":0,"publisher":{"@id":"https:\/\/diamondtvzambia.com\/#organization"},"image":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#primaryimage"},"thumbnailUrl":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1-1024x607.jpg","articleSection":["Sports"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/","url":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/","name":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN - Diamond Media","isPartOf":{"@id":"https:\/\/diamondtvzambia.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#primaryimage"},"image":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#primaryimage"},"thumbnailUrl":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1-1024x607.jpg","datePublished":"2022-09-23T06:22:31+00:00","dateModified":"2022-09-23T06:22:47+00:00","breadcrumb":{"@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#primaryimage","url":"https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1.jpg?fit=1080%2C640&ssl=1","contentUrl":"https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2022\/09\/chipolopolo-1.jpg?fit=1080%2C640&ssl=1","width":1080,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/diamondtvzambia.com\/staging\/7839\/eagles-of-mali-geared-for-chipolopolo-showdown\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/diamondtvzambia.com\/staging\/7839\/"},{"@type":"ListItem","position":2,"name":"EAGLES OF MALI GEARED FOR CHIPOLOPOLO SHOWDOWN"}]},{"@type":"WebSite","@id":"https:\/\/diamondtvzambia.com\/#website","url":"https:\/\/diamondtvzambia.com\/","name":"Diamond Media","description":"","publisher":{"@id":"https:\/\/diamondtvzambia.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diamondtvzambia.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/diamondtvzambia.com\/#organization","name":"Diamond Media","url":"https:\/\/diamondtvzambia.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/diamondtvzambia.com\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2024\/08\/cropped-Logo.png?fit=999%2C999&ssl=1","contentUrl":"https:\/\/i0.wp.com\/diamondtvzambia.com\/staging\/7839\/wp-content\/uploads\/2024\/08\/cropped-Logo.png?fit=999%2C999&ssl=1","width":999,"height":999,"caption":"Diamond Media"},"image":{"@id":"https:\/\/diamondtvzambia.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/web.facebook.com\/DiamondTvOnline\/","https:\/\/x.com\/diamondtvzambia","https:\/\/www.instagram.com\/diamondtvsocial\/"]},{"@type":"Person","@id":"https:\/\/diamondtvzambia.com\/#\/schema\/person\/9ae61b26a35a38fd83acb1b9f7f4452b","name":"Editor 2","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/52331c099be5016e4ead90a1b22019537520b80ea8d3cc4ce734bd2293679c70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/52331c099be5016e4ead90a1b22019537520b80ea8d3cc4ce734bd2293679c70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/52331c099be5016e4ead90a1b22019537520b80ea8d3cc4ce734bd2293679c70?s=96&d=mm&r=g","caption":"Editor 2"},"url":"https:\/\/diamondtvzambia.com\/staging\/7839\/author\/editor-2\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/posts\/1121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/comments?post=1121"}],"version-history":[{"count":1,"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/posts\/1121\/revisions"}],"predecessor-version":[{"id":1123,"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/posts\/1121\/revisions\/1123"}],"wp:attachment":[{"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/media?parent=1121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/categories?post=1121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diamondtvzambia.com\/staging\/7839\/wp-json\/wp\/v2\/tags?post=1121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}